{"id":4748,"date":"2026-03-25T07:30:00","date_gmt":"2026-03-25T06:30:00","guid":{"rendered":"https:\/\/www.gobiernolocal.org\/acento-local\/?p=4748"},"modified":"2026-03-18T12:37:45","modified_gmt":"2026-03-18T11:37:45","slug":"es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos","status":"publish","type":"post","link":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/","title":{"rendered":"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos?"},"content":{"rendered":"\n<p>La Sentencia 626\/2025, de 26 de mayo, del Tribunal Supremo ha valorado y resuelto negativamente la posibilidad de que los convenios sean susceptibles de revisi\u00f3n de oficio, si bien circunscrito al \u00e1mbito de los convenios interadministrativos.<\/p>\n\n\n\n<p>La cuesti\u00f3n controvertida ten\u00eda su origen en un acuerdo del pleno de una corporaci\u00f3n local por el que se declaraba la revisi\u00f3n de oficio de un convenio suscrito entre esta y un Ministerio. La defensa del ayuntamiento esgrim\u00eda que se trataba de una forma de terminaci\u00f3n convencional, por lo que, finalizado el procedimiento administrativo, resultar\u00eda aplicable la regulaci\u00f3n de los actos administrativos, siendo posible, consecuentemente, la revisi\u00f3n de oficio de los actos nulos de pleno derecho.<\/p>\n\n\n\n<p>Sin embargo, la Sala de instancia no apreci\u00f3 que el convenio objeto de la litis tuviera naturaleza de terminaci\u00f3n convencional; por el contrario, consider\u00f3 que se estaba en presencia de un convenio interadministrativo.<\/p>\n\n\n\n<p>De aceptarse la tesis del ayuntamiento \u2014dec\u00eda la Sala de instancia\u2014 se estar\u00eda consiguiendo una decisi\u00f3n unilateral sobre los derechos y obligaciones que vinculan a la otra Administraci\u00f3n p\u00fablica contraparte y, en \u00faltima instancia, se estar\u00eda resolviendo en el mismo acto que declara la nulidad sus consecuencias, lo que era claramente irrespetuoso con el principio general de que los contratos no pueden quedar al arbitrio de uno de los contratantes.<\/p>\n\n\n\n<p>Se a\u00f1ad\u00eda que se hab\u00eda actuado como si se tratara de un contrato de los que regula la Ley de Contratos P\u00fablicos, con activaci\u00f3n de los privilegios consustanciales a las entidades contratantes, olvidando que los convenios est\u00e1n excluidos precisamente de dicho r\u00e9gimen jur\u00eddico, y se concluye que la Ley de R\u00e9gimen Jur\u00eddico del Sector P\u00fablico (LRJSP) no contempla en su art\u00edculo 51 como causa de extinci\u00f3n de los convenios la revisi\u00f3n de oficio, en buena l\u00f3gica por su car\u00e1cter bilateral, el principio de lealtad y de igualdad; por el contrario, se apunta directamente en dicho precepto a la necesaria decisi\u00f3n judicial para la declaraci\u00f3n de la nulidad del convenio.<\/p>\n\n\n\n<p>El Tribunal Supremo, por su parte, secunda las tesis sostenidas por la Sala de instancia, matizando que la cuesti\u00f3n va a ser analizada, exclusivamente, desde la perspectiva de la naturaleza jur\u00eddica que reviste el convenio, de modo que, atendido su contenido, se concluye que se trata de un convenio interadministrativo, en la definici\u00f3n que de esta categor\u00eda jur\u00eddica realiza ahora el art\u00edculo 47.2.a) de la LRJSP, y, por tanto, hall\u00e1ndose sujeto a la regulaci\u00f3n contenida en dicho cuerpo normativo.<\/p>\n\n\n\n<p>A continuaci\u00f3n, nos recuerda que la revisi\u00f3n de oficio constituye una potestad p\u00fablica excepcional, prevista por el legislador como una proyecci\u00f3n de la potestad de autotutela administrativa, en cuanto permite a las Administraciones enervar el principio de que nadie puede ir contra sus propios actos \u2014<em>non licet venire contra factum proprium<\/em>\u2014,as\u00ed como el principio de irrevocabilidad de los actos favorables a los interesados. Prosigue acentuando los importantes l\u00edmites que aquilatan la revisi\u00f3n de oficio, y de entre ellos destaca el propio \u00e1mbito objetivo sobre el que se ejerce esta v\u00eda revisora excepcional.<\/p>\n\n\n\n<p>Se asevera que un convenio interadministrativo no puede resultar objeto del procedimiento de revisi\u00f3n de oficio previsto en el art\u00edculo 106 de la LRJSP, puesto que no aparece mencionado en el mismo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>Se asevera que un convenio interadministrativo no puede resultar objeto del procedimiento de revisi\u00f3n de oficio previsto en el art\u00edculo 106 de la LRJSP, puesto que no aparece mencionado en el mismo.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>Se apela, efectivamente, a la dicci\u00f3n literal del citado precepto, de modo que la posibilidad de revisi\u00f3n solo es predicable de las disposiciones administrativas o de actos administrativos que hubiesen puesto fin a la v\u00eda administrativa o no hubiesen sido recurridos en plazo, precisando que un convenio interadministrativo no supone ni lo uno ni lo otro, pues carece de la unilateralidad propia de aquellos, subyaciendo, en verdad, un negocio jur\u00eddico de car\u00e1cter bilateral o multilateral, seg\u00fan resulta de la definici\u00f3n realizada en el art\u00edculo 47.1 de la LRJSP.<\/p>\n\n\n\n<p>Prosigue confrontando la dis\u00edmil posici\u00f3n que ostenta la Administraci\u00f3n en sede contractual versus convencional, de modo que, a diferencia de los contratos p\u00fablicos en los que la Administraci\u00f3n ocupa una posici\u00f3n de privilegio por raz\u00f3n de los intereses p\u00fablicos imbricados en el contrato que solo a ella corresponde tutelar, \u201clo que implica el posible ejercicio de determinadas prerrogativas no reconocidas a las partes contratantes en los contratos privados\u201d, en los convenios interadministrativos ambas partes representan intereses p\u00fablicos no subordinados entre s\u00ed, \u201clo que impide la adopci\u00f3n de decisiones unilaterales, m\u00e1xime cuando son de gran intensidad como lo es la revisi\u00f3n de oficio, de la que derivar\u00eda la nulidad del propio convenio, sin participaci\u00f3n de la otra Administraci\u00f3n\u201d (F. J. 6).<\/p>\n\n\n\n<p>Insiste tambi\u00e9n en que los convenios interadministrativos quedan extramuros del \u00e1mbito de aplicaci\u00f3n de la Ley del Procedimiento Administrativo Com\u00fan de las Administraciones P\u00fablicas (LPAC), definido en su art\u00edculo 1.1. Rep\u00e1rese en que en este cuerpo legal es donde se regula la revisi\u00f3n de oficio.<\/p>\n\n\n\n<p>Se niega igualmente que se est\u00e9 en presencia de un acuerdo convencional de terminaci\u00f3n de un procedimiento administrativo, e impl\u00edcitamente se reconoce que tampoco los convenios finalizadores del procedimiento administrativo podr\u00edan ser susceptibles de revisi\u00f3n de oficio.<\/p>\n\n\n\n<p>Se atiende finalmente al r\u00e9gimen jur\u00eddico de la resoluci\u00f3n de los convenios, en coherencia con la calificaci\u00f3n dada al instrumento objeto del litigio, recordando que el art\u00edculo 51 de la LRJSP no auspicia la posibilidad de revisi\u00f3n de oficio de los convenios, aunque s\u00ed la declaraci\u00f3n de nulidad por parte de un \u00f3rgano judicial. Y cree comprender esa decisi\u00f3n del legislador en el car\u00e1cter bilateral o multilateral que caracteriza a los convenios, lo que supone una inevitable dificultad para el reconocimiento de este tipo de potestad unidireccional, por su clara afectaci\u00f3n del principio de seguridad jur\u00eddica. Esta complicaci\u00f3n se muestra especialmente significativa \u2014seg\u00fan la sentencia\u2014 en el caso de los convenios interadministrativos, en los que concurren las voluntades de dos o m\u00e1s Administraciones. Bajo esta consideraci\u00f3n, resultar\u00eda dif\u00edcil entender y justificar el ejercicio de una potestad, como la revisora, que ser\u00eda ejercida por una de las Administraciones participantes y que permitir\u00eda a esta la declaraci\u00f3n unilateral de la nulidad del convenio sin que concurriese la voluntad de las restantes Administraciones que lo hubieran suscrito.<\/p>\n\n\n\n<p>En virtud de todos los razonamientos anteriores se fija como doctrina jurisprudencial que \u201clos convenios interadministrativos que celebran las Administraciones P\u00fablicas no son susceptibles de ser revisados de oficio a trav\u00e9s del procedimiento regulado en el citado art\u00edculo 106 de la ley 39\/2015 por lo que, en caso de apreciarse la existencia de un vicio de nulidad en los mismos, la declaraci\u00f3n de nulidad deber\u00e1 producirse por resoluci\u00f3n judicial\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>En virtud de todos los razonamientos anteriores se fija como doctrina jurisprudencial que \u201clos convenios interadministrativos que celebran las Administraciones P\u00fablicas no son susceptibles de ser revisados de oficio a trav\u00e9s del procedimiento regulado en el citado art\u00edculo 106 de la ley 39\/2015 por lo que, en caso de apreciarse la existencia de un vicio de nulidad en los mismos, la declaraci\u00f3n de nulidad deber\u00e1 producirse por resoluci\u00f3n judicial\u201d.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>Restar\u00eda conjeturar sobre si esta misma doctrina resultar\u00eda extensible a los convenios suscritos con sujetos de derecho privado, sabiendo que la doctrina administrativista se halla dividida. A nuestro entender, el <em>excursus<\/em> desarrollado en la sentencia analizada permitir\u00eda negar la potestad revisora tambi\u00e9n en estos supuestos, puesto que los argumentos esgrimidos en orden a la adecuada delimitaci\u00f3n de los contornos de la revisi\u00f3n de oficio, el propio \u00e1mbito de aplicaci\u00f3n de la LPAC o la diferente posici\u00f3n ostentada por las Administraciones en el \u00e1mbito contractual o convencional, resultan igualmente trasladables a cualquier convenio, incluidos los celebrados con sujetos de derecho privado.<\/p>\n\n\n\n<p>Autor\/a:&nbsp;<strong>Fernando Luque Regueiro<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\"><em>imagen: <\/em><a href=\"https:\/\/www.istockphoto.com\/es\/portfolio\/VolhaRahalskaya?mediatype=photography\">\u00abiStock.com\/Volha Rahalskaya\u00bb<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tribunal Supremo resuelve las dudas doctrinales sobre si es dable acudir al procedimiento de revisi\u00f3n de oficio para declarar la nulidad de los convenios interadministrativos. Los argumentos aducidos ser\u00edan aplicables tambi\u00e9n a los convenios suscritos con sujetos de derecho privado.<\/p>\n","protected":false},"author":2,"featured_media":4750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"area-autor":{"item-0":{"nombre-del-autor":"Fernando Luque Regueiro","cargo-autor":"Letrado de la Comunidad de Madrid. Cruz Distinguida (1.\u00aa Clase) de la Orden de San Raimundo de Pe\u00f1afort","foto-autor":"4749"}},"footnotes":""},"categories":[7],"tags":[59,82,142],"autor-post":[184],"class_list":["post-4748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobernanza","tag-contratos","tag-convenios","tag-procedimiento-administrativo","autor-post-fernando-luque-regueiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos? - Fundaci\u00f3n Democracia y Gobierno Local<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos? - Fundaci\u00f3n Democracia y Gobierno Local\" \/>\n<meta property=\"og:description\" content=\"El Tribunal Supremo resuelve las dudas doctrinales sobre si es dable acudir al procedimiento de revisi\u00f3n de oficio para declarar la nulidad de los convenios interadministrativos. Los argumentos aducidos ser\u00edan aplicables tambi\u00e9n a los convenios suscritos con sujetos de derecho privado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Democracia y Gobierno Local\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T06:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fundaci\u00f3n Gobierno Local\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fundaci\u00f3n Gobierno Local\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/\"},\"author\":{\"name\":\"Fundaci\u00f3n Gobierno Local\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c\"},\"headline\":\"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos?\",\"datePublished\":\"2026-03-25T06:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/\"},\"wordCount\":1397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg\",\"keywords\":[\"Contratos\",\"Convenios\",\"Procedimiento administrativo\"],\"articleSection\":[\"Gobernanza\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/\",\"name\":\"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos? - Fundaci\u00f3n Democracia y Gobierno Local\",\"isPartOf\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg\",\"datePublished\":\"2026-03-25T06:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#primaryimage\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg\",\"contentUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#website\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\",\"name\":\"Fundaci\u00f3n Democracia y Gobierno Local\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gobiernolocal.org\/acento-local\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\",\"name\":\"Fundaci\u00f3n Democracia y Gobierno Local\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png\",\"contentUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png\",\"width\":1005,\"height\":197,\"caption\":\"Fundaci\u00f3n Democracia y Gobierno Local\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c\",\"name\":\"Fundaci\u00f3n Gobierno Local\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g\",\"caption\":\"Fundaci\u00f3n Gobierno Local\"},\"sameAs\":[\"https:\/\/www.gobiernolocal.org\/acento-local\"],\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/author\/fundacion-gobierno-local\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos? - Fundaci\u00f3n Democracia y Gobierno Local","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos? - Fundaci\u00f3n Democracia y Gobierno Local","og_description":"El Tribunal Supremo resuelve las dudas doctrinales sobre si es dable acudir al procedimiento de revisi\u00f3n de oficio para declarar la nulidad de los convenios interadministrativos. Los argumentos aducidos ser\u00edan aplicables tambi\u00e9n a los convenios suscritos con sujetos de derecho privado.","og_url":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/","og_site_name":"Fundaci\u00f3n Democracia y Gobierno Local","article_published_time":"2026-03-25T06:30:00+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg","type":"image\/jpeg"}],"author":"Fundaci\u00f3n Gobierno Local","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fundaci\u00f3n Gobierno Local","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#article","isPartOf":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/"},"author":{"name":"Fundaci\u00f3n Gobierno Local","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c"},"headline":"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos?","datePublished":"2026-03-25T06:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/"},"wordCount":1397,"commentCount":0,"publisher":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg","keywords":["Contratos","Convenios","Procedimiento administrativo"],"articleSection":["Gobernanza"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/","url":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/","name":"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos? - Fundaci\u00f3n Democracia y Gobierno Local","isPartOf":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#primaryimage"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg","datePublished":"2026-03-25T06:30:00+00:00","breadcrumb":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#primaryimage","url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg","contentUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260325_800_01.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/es-posible-la-revision-de-oficio-de-los-convenios-interadministrativos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.gobiernolocal.org\/acento-local\/"},{"@type":"ListItem","position":2,"name":"\u00bfEs posible la revisi\u00f3n de oficio de los convenios interadministrativos?"}]},{"@type":"WebSite","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#website","url":"https:\/\/www.gobiernolocal.org\/acento-local\/","name":"Fundaci\u00f3n Democracia y Gobierno Local","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gobiernolocal.org\/acento-local\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization","name":"Fundaci\u00f3n Democracia y Gobierno Local","url":"https:\/\/www.gobiernolocal.org\/acento-local\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/","url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png","contentUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png","width":1005,"height":197,"caption":"Fundaci\u00f3n Democracia y Gobierno Local"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c","name":"Fundaci\u00f3n Gobierno Local","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g","caption":"Fundaci\u00f3n Gobierno Local"},"sameAs":["https:\/\/www.gobiernolocal.org\/acento-local"],"url":"https:\/\/www.gobiernolocal.org\/acento-local\/author\/fundacion-gobierno-local\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts\/4748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/comments?post=4748"}],"version-history":[{"count":1,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts\/4748\/revisions"}],"predecessor-version":[{"id":4751,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts\/4748\/revisions\/4751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/media\/4750"}],"wp:attachment":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/media?parent=4748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/categories?post=4748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/tags?post=4748"},{"taxonomy":"autor-post","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/autor-post?post=4748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}