{"id":4744,"date":"2026-03-20T07:30:00","date_gmt":"2026-03-20T06:30:00","guid":{"rendered":"https:\/\/www.gobiernolocal.org\/acento-local\/?p=4744"},"modified":"2026-03-25T09:39:47","modified_gmt":"2026-03-25T08:39:47","slug":"si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025","status":"publish","type":"post","link":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/","title":{"rendered":"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.poderjudicial.es\/search\/AN\/openDocument\/64e9048de1ff0286a0a8778d75e36f0d\/20260108\"><strong>Sentencia del Tribunal Supremo (Sala de lo Contencioso-Administrativo, Secci\u00f3n Tercera) n\u00fam. 1686\/2025, de 18 de diciembre (ECLI:ES:TS:2025:5961)<\/strong><\/a>:<\/p>\n\n\n\n<p><strong>RECURSO DE CASACI\u00d3N: ANTECEDENTES<\/strong><\/p>\n\n\n\n<p>Debido a los incumplimientos detectados por los servicios municipales, la Junta de Gobierno Local del Ayuntamiento de Parla (Madrid) acord\u00f3 resolver el contrato firmado con Los Lagos del Este, Sociedad Cooperativa Madrile\u00f1a, en relaci\u00f3n con el derecho de superficie constituido sobre unas parcelas para la construcci\u00f3n de complejos residenciales, su explotaci\u00f3n y su destino para fines sociales dirigidos a colectivos vulnerables. Adem\u00e1s de ello, procedi\u00f3 a la incautaci\u00f3n de la garant\u00eda y a la apertura de un procedimiento de fijaci\u00f3n y valoraci\u00f3n de da\u00f1os y perjuicios causados a la Administraci\u00f3n. Frente a esta decisi\u00f3n, la Cooperativa interpuso recurso contencioso-administrativo, que fue desestimado por el Juzgado de lo Contencioso-Administrativo n\u00fam. 8 de Madrid.<\/p>\n\n\n\n<p>Notificada la sentencia, la Cooperativa interpuso recurso de apelaci\u00f3n contra la anterior, tambi\u00e9n desestimado por la Secci\u00f3n Segunda de la Sala de lo Contencioso-Administrativo del Tribunal Superior de Justicia de Madrid. En esta ocasi\u00f3n, la Sala confirm\u00f3 que el contrato de constituci\u00f3n de un derecho de superficie respond\u00eda \u201ca la definici\u00f3n de contrato privado de los contemplados en el n\u00famero 2 del art\u00edculo 9 de la Ley 9\/2017, de CSP, pues su naturaleza es an\u00e1loga a un contrato de compraventa o arrendamiento, expresamente excluidos de la aplicaci\u00f3n de la Ley de Contratos del Sector P\u00fablico\u201d, lo que determina \u201cque esta jurisdicci\u00f3n contencioso-administrativa no deba pronunciarse sobre la extinci\u00f3n del contrato privado\u201d, como \u2014afirma\u2014 no debi\u00f3 haber hecho el Juzgado sobre cuestiones de naturaleza civil.<\/p>\n\n\n\n<p><strong>JUICIO DE LA SALA<\/strong><\/p>\n\n\n\n<p>Contra esta sentencia, la Cooperativa interpuso recurso de casaci\u00f3n, siendo admitido por la Sala Cuarta del Tribunal Supremo, que identific\u00f3 el inter\u00e9s casacional objetivo para la formaci\u00f3n de jurisprudencia consistente en determinar: \u201cSi el contrato de constituci\u00f3n de derecho de superficie sobre terrenos de propiedad municipal destinados directamente al servicio p\u00fablico de dotaci\u00f3n de vivienda social a colectivos vulnerables (j\u00f3venes y personas de la tercera edad) es un contrato administrativo especial o un contrato privado, a los efectos de poder determinar el orden jurisdiccional competente\u201d.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>La Sala Cuarta del Tribunal Supremo<\/strong>, <strong>identific\u00f3 el inter\u00e9s casacional objetivo para la formaci\u00f3n de jurisprudencia consistente en determinar: \u201cSi el contrato de constituci\u00f3n de derecho de superficie sobre terrenos de propiedad municipal destinados directamente al servicio p\u00fablico de dotaci\u00f3n de vivienda social a colectivos vulnerables (j\u00f3venes y personas de la tercera edad) es un contrato administrativo especial o un contrato privado, a los efectos de poder determinar el orden jurisdiccional competente\u201d.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>De un lado, el Ayuntamiento de Parla sostuvo que la Cooperativa incurri\u00f3 en incumplimientos graves de sus obligaciones seg\u00fan lo detallado en informes t\u00e9cnicos municipales, motivo por el cual la Junta de Gobierno Local acord\u00f3 la resoluci\u00f3n del contrato, la extinci\u00f3n del derecho de superficie, la reversi\u00f3n de las parcelas y el resto de procedimientos ya indicados. Salvo en su oposici\u00f3n al recurso de casaci\u00f3n (calificado como \u201cde dif\u00edcil comprender\u201d), siempre defendi\u00f3 que el contrato de constituci\u00f3n de derecho de superficie era de naturaleza privada, lo que le permiti\u00f3 resolverlo al amparo de las cl\u00e1usulas recogidas en los pliegos de cl\u00e1usulas administrativas y de prescripciones t\u00e9cnicas, sin necesidad de seguir los tr\u00e1mites exigidos por la Ley de Contratos del Sector P\u00fablico para los contratos administrativos.<\/p>\n\n\n\n<p>Al contrario, Los Lagos del Este, Sociedad Cooperativa Madrile\u00f1a, insisti\u00f3 en la impugnaci\u00f3n de la resoluci\u00f3n del contrato en cada instancia, sosteniendo su nulidad por no haber seguido el procedimiento legalmente establecido para los contratos administrativos. La Coordinadora siempre ha considerado que se trataba de un contrato administrativo especial por estar destinado de forma \u00abdirecta e inmediata\u00bb a la satisfacci\u00f3n de una finalidad p\u00fablica: la dotaci\u00f3n de vivienda social para colectivos vulnerables (una competencia espec\u00edfica municipal seg\u00fan la Ley de Bases del R\u00e9gimen Local).<\/p>\n\n\n\n<p>En esa misma l\u00ednea razona el Tribunal Supremo en la sentencia analizada, que \u2014conforme a la siguiente argumentaci\u00f3n\u2014 se centra en determinar la naturaleza jur\u00eddica del contrato para establecer despu\u00e9s si el Ayuntamiento de Parla actu\u00f3 legalmente al resolverlo.<\/p>\n\n\n\n<p>En primer lugar, el Tribunal \u2014recordando que la naturaleza de un contrato no depende de la denominaci\u00f3n que le otorguen las partes, sino de su causa y finalidad\u2014 acoge el criterio de que \u201cla relaci\u00f3n jur\u00eddica concreta ofrece naturaleza administrativa cuando en su causa se advierte la presencia de un fin p\u00fablico como elemento esencial, no actuando como cualquier entidad privada, pues si as\u00ed lo hace, el negocio tendr\u00e1 car\u00e1cter privado\u201d. En segundo lugar, aunque la Ley de Contratos del Sector P\u00fablico excluye del \u00e1mbito administrativo los negocios sobre bienes inmuebles (como compraventas o arrendamientos), el Supremo aclara que esta exclusi\u00f3n solo se aplica cuando el inter\u00e9s de la Administraci\u00f3n es puramente econ\u00f3mico o mercantil, \u201cajeno al desenvolvimiento regular de un servicio p\u00fablico o a la satisfacci\u00f3n de una necesidad p\u00fablica de su competencia\u201d. En tercer lugar, cuando el contrato de derecho de superficie se utiliza para alcanzar fines que son competencia espec\u00edfica de la Administraci\u00f3n (como en el caso, la vivienda social), no se trata de un mero \u00abnegocio patrimonial\u00bb, sino de un contrato administrativo especial.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>Cuando el contrato de derecho de superficie se utiliza para alcanzar fines que son competencia espec\u00edfica de la Administraci\u00f3n (como en el caso, la vivienda social), no se trata de un mero \u00abnegocio patrimonial\u00bb, sino de un contrato administrativo especial.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>Por tanto, a juicio del Tribunal, \u201cel contrato del derecho de superficie constituido sobre determinadas parcelas municipales a favor de, entre otras sociedades, la recurrente, para satisfacer una finalidad p\u00fablica de la espec\u00edfica competencia del Ayuntamiento, no puede calificarse de negocio jur\u00eddico sobre bienes inmuebles excluido del \u00e1mbito objetivo de aplicaci\u00f3n de la Ley de Contratos ni, en su suma, de contrato privado, como err\u00f3neamente ha apreciado la sentencia de la Sala de apelaci\u00f3n y, antes la de la primera instancia\u201d. De ah\u00ed que fije como doctrina que, si la finalidad principal de un derecho de superficie sobre bienes municipales es satisfacer un inter\u00e9s p\u00fablico de competencia espec\u00edfica del Ayuntamiento, se debe rechazar su calificaci\u00f3n como contrato privado y considerarlo un contrato administrativo especial seg\u00fan el art\u00edculo 19 de la Ley 30\/2007 (actual art\u00edculo 25 de la Ley 9\/2017) de Contratos del Sector P\u00fablico.<\/p>\n\n\n\n<p>En consecuencia, dado su car\u00e1cter administrativo, su resoluci\u00f3n exig\u00eda un procedimiento estricto del que se ha prescindido, y \u201cque no es una simple omisi\u00f3n formal intrascendente sino que da lugar a que concurra la causa de nulidad de pleno derecho prevista en la Ley de Procedimiento Administrativo\u201d. En cambio, el Ayuntamiento de Parla solo realiz\u00f3 informes internos y, aunque dio audiencia a la Cooperativa, omiti\u00f3 el informe preceptivo del Servicio Jur\u00eddico de la entidad local y del Consejo Consultivo de la Comunidad de Madrid. Por lo tanto, dicha omisi\u00f3n determina la nulidad de pleno derecho del acto administrativo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>En consecuencia, dado su car\u00e1cter administrativo, su resoluci\u00f3n exig\u00eda un procedimiento estricto del que se ha prescindido, y \u201cque no es una simple omisi\u00f3n formal intrascendente sino que da lugar a que concurra la causa de nulidad de pleno derecho prevista en la Ley de Procedimiento Administrativo\u201d.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>En definitiva, el Tribunal Supremo establece que para calificar estos contratos debe atenderse al fin de los mismos, y no solo al objeto sobre el que recaen, de modo que, si la finalidad principal del contrato es satisfacer un inter\u00e9s p\u00fablico de competencia espec\u00edfica del Ayuntamiento, el contrato debe considerarse administrativo especial.<\/p>\n\n\n\n<p>Autor\/a:&nbsp;<strong>Ana Garc\u00eda Garc\u00eda<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\"><em>imagen: <\/em><a href=\"https:\/\/www.istockphoto.com\/es\/portfolio\/JTKPHOTOz?mediatype=photography\">\u00abiStock.com\/JTKPHOTOz\u00bb<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la sentencia del Tribunal Supremo n\u00fam. 1541\/2025, de 27 de noviembre, se establece que el derecho de superficie para fines sociales es un contrato administrativo especial por su vinculaci\u00f3n a competencias municipales, siendo nula de pleno derecho la resoluci\u00f3n del Ayuntamiento de Parla por omitir el dictamen preceptivo del \u00f3rgano consultivo.<br \/>\nSENTIDO DEL FALLO: recurso de casaci\u00f3n, estimaci\u00f3n del recurso de casaci\u00f3n.<\/p>\n","protected":false},"author":2,"featured_media":4745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"area-autor":{"item-0":{"nombre-del-autor":"Ana Garc\u00eda Garc\u00eda","cargo-autor":"Profesora ayudante doctora. Universidad de Burgos","foto-autor":""}},"footnotes":""},"categories":[172],"tags":[59,243],"autor-post":[242],"class_list":["post-4744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jurisprudencia","tag-contratos","tag-jurisdiccion","autor-post-ana-garcia-garcia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025 - Fundaci\u00f3n Democracia y Gobierno Local<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025 - Fundaci\u00f3n Democracia y Gobierno Local\" \/>\n<meta property=\"og:description\" content=\"En la sentencia del Tribunal Supremo n\u00fam. 1541\/2025, de 27 de noviembre, se establece que el derecho de superficie para fines sociales es un contrato administrativo especial por su vinculaci\u00f3n a competencias municipales, siendo nula de pleno derecho la resoluci\u00f3n del Ayuntamiento de Parla por omitir el dictamen preceptivo del \u00f3rgano consultivo. SENTIDO DEL FALLO: recurso de casaci\u00f3n, estimaci\u00f3n del recurso de casaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Democracia y Gobierno Local\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T06:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T08:39:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fundaci\u00f3n Gobierno Local\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fundaci\u00f3n Gobierno Local\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/\"},\"author\":{\"name\":\"Fundaci\u00f3n Gobierno Local\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c\"},\"headline\":\"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025\",\"datePublished\":\"2026-03-20T06:30:00+00:00\",\"dateModified\":\"2026-03-25T08:39:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/\"},\"wordCount\":1364,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg\",\"keywords\":[\"Contratos\",\"Jurisdicci\u00f3n\"],\"articleSection\":[\"Jurisprudencia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/\",\"name\":\"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025 - Fundaci\u00f3n Democracia y Gobierno Local\",\"isPartOf\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg\",\"datePublished\":\"2026-03-20T06:30:00+00:00\",\"dateModified\":\"2026-03-25T08:39:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#primaryimage\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg\",\"contentUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#website\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\",\"name\":\"Fundaci\u00f3n Democracia y Gobierno Local\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gobiernolocal.org\/acento-local\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\",\"name\":\"Fundaci\u00f3n Democracia y Gobierno Local\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png\",\"contentUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png\",\"width\":1005,\"height\":197,\"caption\":\"Fundaci\u00f3n Democracia y Gobierno Local\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c\",\"name\":\"Fundaci\u00f3n Gobierno Local\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g\",\"caption\":\"Fundaci\u00f3n Gobierno Local\"},\"sameAs\":[\"https:\/\/www.gobiernolocal.org\/acento-local\"],\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/author\/fundacion-gobierno-local\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025 - Fundaci\u00f3n Democracia y Gobierno Local","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025 - Fundaci\u00f3n Democracia y Gobierno Local","og_description":"En la sentencia del Tribunal Supremo n\u00fam. 1541\/2025, de 27 de noviembre, se establece que el derecho de superficie para fines sociales es un contrato administrativo especial por su vinculaci\u00f3n a competencias municipales, siendo nula de pleno derecho la resoluci\u00f3n del Ayuntamiento de Parla por omitir el dictamen preceptivo del \u00f3rgano consultivo. SENTIDO DEL FALLO: recurso de casaci\u00f3n, estimaci\u00f3n del recurso de casaci\u00f3n.","og_url":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/","og_site_name":"Fundaci\u00f3n Democracia y Gobierno Local","article_published_time":"2026-03-20T06:30:00+00:00","article_modified_time":"2026-03-25T08:39:47+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg","type":"image\/jpeg"}],"author":"Fundaci\u00f3n Gobierno Local","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fundaci\u00f3n Gobierno Local","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#article","isPartOf":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/"},"author":{"name":"Fundaci\u00f3n Gobierno Local","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c"},"headline":"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025","datePublished":"2026-03-20T06:30:00+00:00","dateModified":"2026-03-25T08:39:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/"},"wordCount":1364,"commentCount":0,"publisher":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg","keywords":["Contratos","Jurisdicci\u00f3n"],"articleSection":["Jurisprudencia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/","url":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/","name":"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025 - Fundaci\u00f3n Democracia y Gobierno Local","isPartOf":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg","datePublished":"2026-03-20T06:30:00+00:00","dateModified":"2026-03-25T08:39:47+00:00","breadcrumb":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#primaryimage","url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg","contentUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2026\/03\/260320_800_01.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/si-un-contrato-sobre-bienes-inmuebles-atiende-a-una-finalidad-publica-debe-considerarse-como-contrato-administrativo-especial-sentencia-del-tribunal-supremo-1686-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.gobiernolocal.org\/acento-local\/"},{"@type":"ListItem","position":2,"name":"Si un contrato sobre bienes inmuebles atiende a una finalidad p\u00fablica, debe considerarse como contrato administrativo especial. Sentencia del Tribunal Supremo 1686\/2025"}]},{"@type":"WebSite","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#website","url":"https:\/\/www.gobiernolocal.org\/acento-local\/","name":"Fundaci\u00f3n Democracia y Gobierno Local","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gobiernolocal.org\/acento-local\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization","name":"Fundaci\u00f3n Democracia y Gobierno Local","url":"https:\/\/www.gobiernolocal.org\/acento-local\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/","url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png","contentUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png","width":1005,"height":197,"caption":"Fundaci\u00f3n Democracia y Gobierno Local"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c","name":"Fundaci\u00f3n Gobierno Local","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g","caption":"Fundaci\u00f3n Gobierno Local"},"sameAs":["https:\/\/www.gobiernolocal.org\/acento-local"],"url":"https:\/\/www.gobiernolocal.org\/acento-local\/author\/fundacion-gobierno-local\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts\/4744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/comments?post=4744"}],"version-history":[{"count":2,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts\/4744\/revisions"}],"predecessor-version":[{"id":4747,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts\/4744\/revisions\/4747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/media\/4745"}],"wp:attachment":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/media?parent=4744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/categories?post=4744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/tags?post=4744"},{"taxonomy":"autor-post","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/autor-post?post=4744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}