{"id":3784,"date":"2024-09-25T07:30:00","date_gmt":"2024-09-25T05:30:00","guid":{"rendered":"https:\/\/www.gobiernolocal.org\/acento-local\/?p=3784"},"modified":"2024-09-20T12:20:04","modified_gmt":"2024-09-20T10:20:04","slug":"las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento","status":"publish","type":"post","link":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/","title":{"rendered":"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento"},"content":{"rendered":"\n<p><strong>El problema de base y el auxilio de la colaboraci\u00f3n p\u00fablico-privada<\/strong><\/p>\n\n\n\n<p>Como se ha comentado en <em>posts<\/em> anteriores, resulta una realidad incontestable que numerosos municipios son incapaces de cumplir con los plazos legales fijados para el otorgamiento de licencias urban\u00edsticas y otros tr\u00e1mites vinculados con la actividad de edificaci\u00f3n. Tambi\u00e9n es incontestable que esta situaci\u00f3n causa perjuicios de diversa \u00edndole a ciudadanos y empresas: desde simples molestias a afecciones al derecho constitucional a una vivienda, pasando por la huida de relevantes inversiones econ\u00f3micas. En fin, verdaderos intereses p\u00fablicos afectados. Los motivos de esa incapacidad son muy variados (inadecuadas regulaciones, falta de personal, complejidad t\u00e9cnica, etc.). Las v\u00edas que el legislador estatal, el auton\u00f3mico e incluso algunas ordenanzas municipales sin esperar a esos legisladores han empleado en los \u00faltimos a\u00f1os para revertir esta situaci\u00f3n son tambi\u00e9n variadas, y van desde la reducci\u00f3n del \u00e1mbito de actividades sometidas a esos controles previos hasta la apuesta por la denominada colaboraci\u00f3n p\u00fablico-privada, que es lo que ahora nos interesa. Esta colaboraci\u00f3n consiste, a grandes rasgos, en posibilitar que entidades privadas intervengan de manera instrumental en estas actuaciones de control del cumplimiento de la normativa, no solo en los controles previos como las licencias, sino tambi\u00e9n en los posteriores como la inspecci\u00f3n urban\u00edstica.<\/p>\n\n\n\n<p>Pues bien, la <a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2021-20916\">Ley 7\/2021, de 1 de diciembre, de impulso para la sostenibilidad del territorio de Andaluc\u00eda<\/a> (en adelante, LISTA), no ha sido una excepci\u00f3n. Su punto de partida es contundente en esta l\u00ednea:\u00a0 las Administraciones p\u00fablicas con competencias en la ordenaci\u00f3n territorial y urban\u00edstica tienen el deber de facilitar y promover la colaboraci\u00f3n de la iniciativa privada en esas actuaciones de control (<em>ex<\/em> art. 9.2)<strong>.<\/strong> Es dif\u00edcil aventurar el alcance real de las consecuencias jur\u00eddicas que tiene que esta colaboraci\u00f3n se configure como un deber legal y no como una mera opci\u00f3n, pero queda clara la relevancia que el legislador ha otorgado a la cuesti\u00f3n. En esa ley se definen las l\u00edneas maestras de dicha colaboraci\u00f3n que despu\u00e9s han sido desarrolladas por el Decreto 550\/2022, de 29 de diciembre, por el que se aprueba el Reglamento General de la LISTA. Debemos destacar que la redacci\u00f3n originaria de ambas normas sobre esta cuesti\u00f3n ha sido notablemente afectada por dos decretos leyes aprobados por el Gobierno andaluz: el <a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOJA-b-2022-90377\">11\/2022, de modificaci\u00f3n de la LISTA<\/a>; y el <a href=\"https:\/\/www.boe.es\/buscar\/doc.php?id=BOJA-b-2024-90030\">3\/2024, de simplificaci\u00f3n administrativa<\/a>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>Las Administraciones p\u00fablicas con competencias en la ordenaci\u00f3n territorial y urban\u00edstica tienen el deber de facilitar y promover la colaboraci\u00f3n de la iniciativa privada en esas actuaciones de control.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p><strong>Tipolog\u00eda de entidades colaboradoras<\/strong><\/p>\n\n\n\n<p>Esa colaboraci\u00f3n se canaliza a trav\u00e9s de dos tipos de entidades: los colegios profesionales (como el de Arquitectos o el de Ingenieros Industriales, por citar dos de los m\u00e1s relevantes en este \u00e1mbito) y las denominadas entidades urban\u00edsticas certificadoras. Los primeros, aunque de base asociativa (los profesionales colegiados), son entidades de derecho p\u00fablico, fundamentalmente porque son creadas por ley y ese legislador les atribuye ciertas funciones p\u00fablicas y define su r\u00e9gimen jur\u00eddico. Las segundas son entidades privadas y solo con ellas se puede hablar con propiedad de colaboraci\u00f3n p\u00fablico-privada. La combinaci\u00f3n de ambas formas de colaboraci\u00f3n sobre un mismo \u00e1mbito, en este caso el urban\u00edstico, plantea dudas sobre el cumplimiento estricto de los principios de libre competencia y objetividad e imparcialidad requeridos para el desempe\u00f1o de funciones p\u00fablicas.<\/p>\n\n\n\n<p><strong>Los \u00e1mbitos de esta colaboraci\u00f3n ni preceptiva, ni excluyente ni vinculante<\/strong><\/p>\n\n\n\n<p>El art. 9.3 LISTA, completado con el art. 13 del Decreto 550\/2022, delimita de la siguiente manera las tareas de colaboraci\u00f3n:<\/p>\n\n\n\n<p>a) Verificar los requisitos de integridad documental, suficiencia e idoneidad de los proyectos y la documentaci\u00f3n correspondientes a la licencia o declaraci\u00f3n responsable, exigidos por la normativa aplicable.<\/p>\n\n\n\n<p>A estos efectos, las entidades colaboradoras podr\u00e1n emitir certificaci\u00f3n de conformidad respecto de la documentaci\u00f3n preceptiva.<\/p>\n\n\n\n<p>b) Comprobar que los proyectos y la documentaci\u00f3n t\u00e9cnica cumplen la normativa t\u00e9cnica aplicable, la legislaci\u00f3n urban\u00edstica y el planeamiento de aplicaci\u00f3n.<\/p>\n\n\n\n<p>A este respecto, podr\u00e1n emitir \u201cinformes previos de conformidad t\u00e9cnica y jur\u00eddica\u201d.<\/p>\n\n\n\n<p>c) Verificar la adecuaci\u00f3n de la ejecuci\u00f3n de las obras a la licencia o a la declaraci\u00f3n responsable.<\/p>\n\n\n\n<p>Estas verificaciones se pueden llevar a cabo tanto de manera previa al inicio de las obras (por ej., actuaciones de comprobaci\u00f3n <em>in situ<\/em> en el solar) como durante su ejecuci\u00f3n o una vez ejecutadas las obras (por ej., a los efectos de la presentaci\u00f3n de la declaraci\u00f3n responsable para la ocupaci\u00f3n o utilizaci\u00f3n). Tambi\u00e9n se podr\u00e1n formalizar mediante certificaciones de conformidad.<\/p>\n\n\n\n<p>d) Colaborar en la realizaci\u00f3n de actuaciones relacionadas con el control del cumplimiento del deber de conservaci\u00f3n.<\/p>\n\n\n\n<p>Estas tareas de colaboraci\u00f3n pueden consistir, entre otras, en la verificaci\u00f3n de los informes de inspecci\u00f3n t\u00e9cnica de las construcciones y en el control administrativo sobre el cumplimiento del deber de conservaci\u00f3n.<\/p>\n\n\n\n<p>El mencionado art. 9 LISTA a\u00f1ade otras dos precisiones muy relevantes en cuanto al r\u00e9gimen jur\u00eddico de esta potencial colaboraci\u00f3n:<\/p>\n\n\n\n<p>1.- En ning\u00fan caso su intervenci\u00f3n ser\u00e1 preceptiva. Por tanto, intervendr\u00e1n bien a instancia de persona interesada en esos procedimientos de control administrativo o bien por encargo de la propia Administraci\u00f3n local.<\/p>\n\n\n\n<p>Esto genera un claro h\u00e1ndicap para la extensi\u00f3n en el empleo de este tipo de entidades por los interesados, pues, en principio, ello supone un mayor coste econ\u00f3mico que solo merecer\u00e1 la pena si lleva aparejadas ventajas jur\u00eddicas (eliminaci\u00f3n de ciertos tr\u00e1mites administrativos, reducci\u00f3n de los plazos de resoluci\u00f3n, etc.) o compensaciones tambi\u00e9n econ\u00f3micas (por ej., reducci\u00f3n en las tasas municipales por la realizaci\u00f3n de estos controles).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>En ning\u00fan caso su intervenci\u00f3n ser\u00e1 preceptiva.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>2.- Sus informes ni son excluyentes ni vinculantes. Los informes, certificados o actas que emitan estas entidades colaboradoras se incorporar\u00e1n al correspondiente expediente administrativo y ser\u00e1n tenidos en cuenta, \u201csin perjuicio de la verificaci\u00f3n y control que en el ejercicio de sus potestades corresponde a la Administraci\u00f3n\u201d. Esto es, ni esos documentos tienen car\u00e1cter vinculante para la Administraci\u00f3n municipal ni excluyen cualquier actuaci\u00f3n de control que la misma considere oportuna (por ej., podr\u00e1 pedir documentaci\u00f3n adicional a pesar de haber aportado el interesado una certificaci\u00f3n de conformidad). En particular, como regla general, el Ayuntamiento debe seguir emitiendo los correspondientes informes t\u00e9cnico y jur\u00eddico en los procedimientos de intervenci\u00f3n administrativa sobre la actividad de edificaci\u00f3n (art. 302 Decreto 550\/2022).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>Sus informes<\/strong> <strong>ni son excluyentes ni vinculantes.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>No obstante, el art. 9 LISTA admite lo siguiente: \u201cLas Ordenanzas municipales podr\u00e1n prever que el informe o certificado pueda surtir efectos equiparables al informe t\u00e9cnico en los procedimientos de intervenci\u00f3n administrativa sobre la actividad de edificaci\u00f3n, en los t\u00e9rminos establecidos reglamentariamente\u201d. Esto es, no ser\u00eda necesaria la emisi\u00f3n del informe t\u00e9cnico si se aporta una certificaci\u00f3n de una entidad colaboradora, pero siempre que as\u00ed lo haya previsto previamente una ordenanza municipal. Adem\u00e1s, esta ordenanza \u201cpodr\u00e1 delimitar aquellas zonas del municipio a las que se podr\u00e1 aplicar el r\u00e9gimen de los informes de las entidades urban\u00edsticas certificadoras y los colegios profesionales, as\u00ed como los tipos de actos urban\u00edsticos sujetos a intervenci\u00f3n administrativa sobre los que podr\u00e1 operar\u201d (art. 15 Reglamento LISTA).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>El art. 9 LISTA admite lo siguiente: \u201cLas Ordenanzas municipales podr\u00e1n prever que el informe o certificado pueda surtir efectos equiparables al informe t\u00e9cnico en los procedimientos de intervenci\u00f3n administrativa sobre la actividad de edificaci\u00f3n, en los t\u00e9rminos establecidos reglamentariamente\u201d.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>Por su parte, el informe jur\u00eddico siempre ser\u00e1 necesario, lo que genera algunos interrogantes, pues, como se ha expuesto, estas entidades pueden emitir un informe de conformidad t\u00e9cnica \u201cy jur\u00eddica\u201d.<\/p>\n\n\n\n<p>De este modo, el legislador andaluz no se atreve a dar directamente un paso decisivo en pro de la utilizaci\u00f3n de estas entidades colaboradoras y se separa, por ej., de lo previsto tanto en los arts. 167 y 167 bis de la <a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2001-18984\">Ley 9\/2001, de 17 de julio, del Suelo, de la Comunidad de Madrid<\/a>, como en el art. 146 bis 3 de la <a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2016-3191\">Ley 2\/2016, de 10 de febrero, del suelo de Galicia<\/a>, donde se parte de que esas actuaciones de dichas entidades sustituyen esos informes t\u00e9cnicos y jur\u00eddicos municipales.<\/p>\n\n\n\n<p>Finalmente, de la literalidad de los arts. 10 y 11 del Decreto 550\/2022 pudiera derivarse otro l\u00edmite adicional: que esos certificados que son susceptibles de sustituir el informe t\u00e9cnico municipal no pueden emitirse a instancia de interesado, sino solo por encargo del Ayuntamiento. El art. 10.2, cuando se refiere a las actuaciones que estas entidades colaboradoras pueden realizar a instancia de persona interesada, se limita a decir:<\/p>\n\n\n\n<p style=\"margin-left:var(--wp--preset--spacing--70)\">\u201cEn estos casos, verificar\u00e1n la documentaci\u00f3n que \u00e9stos les presenten y, en su caso, les advertir\u00e1n de los defectos detectados. Asimismo, podr\u00e1n recabar los informes preceptivos o autorizaciones sectoriales que corresponda solicitar en representaci\u00f3n de los interesados\u201d.<\/p>\n\n\n\n<p>Esto es, solo menciona la funci\u00f3n de verificaci\u00f3n de los requisitos de integridad documental, sin referencia alguna a la funci\u00f3n de comprobaci\u00f3n del cumplimiento de los requisitos t\u00e9cnicos y normativos \u2014que es la que ahora nos ocupa\u2014. Entendemos que se trata de una desafortunada redacci\u00f3n que ha de ser objeto de una interpretaci\u00f3n correctora que resulte armoniosa con lo previsto en el art. 302.1 del mismo decreto, que admite con claridad la posibilidad de que ese informe sea emitido tanto a instancia del Ayuntamiento como de la persona interesada.<\/p>\n\n\n\n<p><strong>Conclusi\u00f3n<\/strong><\/p>\n\n\n\n<p>En definitiva, m\u00e1s all\u00e1 de ciertas proclamaciones grandilocuentes a favor de la colaboraci\u00f3n p\u00fablico-privada en el control del cumplimiento de la normativa urban\u00edstica, el legislador auton\u00f3mico andaluz se ha mostrado muy cauto al respecto en algunos elementos clave y, adem\u00e1s, con ciertas incongruencias normativas internas, que podr\u00edan resolverse mediante un adecuado desarrollo reglamentario a fin de garantizar la eficacia del sistema<strong>.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>M\u00e1s all\u00e1 de ciertas proclamaciones grandilocuentes a favor de la colaboraci\u00f3n p\u00fablico-privada en el control del cumplimiento de la normativa urban\u00edstica, el legislador auton\u00f3mico andaluz se ha mostrado muy cauto al respecto.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p>Autor\/a: <strong>Manuel Izquierdo Carrasco<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La normativa urban\u00edstica andaluza ha realizado formalmente una apuesta decidida por la colaboraci\u00f3n de entidades privadas en las actuaciones municipales de control del cumplimiento de la normativa urban\u00edstica. En este post se analizan los \u00e1mbitos principales de esa colaboraci\u00f3n y sus notas caracter\u00edsticas.<\/p>\n","protected":false},"author":2,"featured_media":3786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"area-autor":{"item-0":{"nombre-del-autor":"Manuel Izquierdo Carrasco","cargo-autor":"Catedr\u00e1tico de Derecho Administrativo. Universidad de C\u00f3rdoba","foto-autor":"3785"}},"footnotes":""},"categories":[7],"tags":[98,142,107],"autor-post":[205],"class_list":["post-3784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobernanza","tag-entidades-colaboradoras","tag-procedimiento-administrativo","tag-urbanismo","autor-post-manuel-izquierdo-carrasco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento - Fundaci\u00f3n Democracia y Gobierno Local<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento - Fundaci\u00f3n Democracia y Gobierno Local\" \/>\n<meta property=\"og:description\" content=\"La normativa urban\u00edstica andaluza ha realizado formalmente una apuesta decidida por la colaboraci\u00f3n de entidades privadas en las actuaciones municipales de control del cumplimiento de la normativa urban\u00edstica. En este post se analizan los \u00e1mbitos principales de esa colaboraci\u00f3n y sus notas caracter\u00edsticas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Democracia y Gobierno Local\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T05:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"593\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fundaci\u00f3n Gobierno Local\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fundaci\u00f3n Gobierno Local\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/\"},\"author\":{\"name\":\"Fundaci\u00f3n Gobierno Local\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c\"},\"headline\":\"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento\",\"datePublished\":\"2024-09-25T05:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/\"},\"wordCount\":1778,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg\",\"keywords\":[\"Entidades colaboradoras\",\"Procedimiento administrativo\",\"Urbanismo\"],\"articleSection\":[\"Gobernanza\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/\",\"name\":\"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento - Fundaci\u00f3n Democracia y Gobierno Local\",\"isPartOf\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg\",\"datePublished\":\"2024-09-25T05:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#primaryimage\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg\",\"contentUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg\",\"width\":800,\"height\":593},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#website\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\",\"name\":\"Fundaci\u00f3n Democracia y Gobierno Local\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gobiernolocal.org\/acento-local\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#organization\",\"name\":\"Fundaci\u00f3n Democracia y Gobierno Local\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png\",\"contentUrl\":\"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png\",\"width\":1005,\"height\":197,\"caption\":\"Fundaci\u00f3n Democracia y Gobierno Local\"},\"image\":{\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c\",\"name\":\"Fundaci\u00f3n Gobierno Local\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g\",\"caption\":\"Fundaci\u00f3n Gobierno Local\"},\"sameAs\":[\"https:\/\/www.gobiernolocal.org\/acento-local\"],\"url\":\"https:\/\/www.gobiernolocal.org\/acento-local\/author\/fundacion-gobierno-local\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento - Fundaci\u00f3n Democracia y Gobierno Local","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento - Fundaci\u00f3n Democracia y Gobierno Local","og_description":"La normativa urban\u00edstica andaluza ha realizado formalmente una apuesta decidida por la colaboraci\u00f3n de entidades privadas en las actuaciones municipales de control del cumplimiento de la normativa urban\u00edstica. En este post se analizan los \u00e1mbitos principales de esa colaboraci\u00f3n y sus notas caracter\u00edsticas.","og_url":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/","og_site_name":"Fundaci\u00f3n Democracia y Gobierno Local","article_published_time":"2024-09-25T05:30:00+00:00","og_image":[{"width":800,"height":593,"url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg","type":"image\/jpeg"}],"author":"Fundaci\u00f3n Gobierno Local","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fundaci\u00f3n Gobierno Local","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#article","isPartOf":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/"},"author":{"name":"Fundaci\u00f3n Gobierno Local","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c"},"headline":"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento","datePublished":"2024-09-25T05:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/"},"wordCount":1778,"commentCount":0,"publisher":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg","keywords":["Entidades colaboradoras","Procedimiento administrativo","Urbanismo"],"articleSection":["Gobernanza"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/","url":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/","name":"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento - Fundaci\u00f3n Democracia y Gobierno Local","isPartOf":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#primaryimage"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg","datePublished":"2024-09-25T05:30:00+00:00","breadcrumb":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#primaryimage","url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg","contentUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/240925_800_01.jpg","width":800,"height":593},{"@type":"BreadcrumbList","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/las-entidades-urbanisticas-colaboradoras-en-andalucia-grandes-proclamaciones-pero-poco-atrevimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.gobiernolocal.org\/acento-local\/"},{"@type":"ListItem","position":2,"name":"Las entidades urban\u00edsticas colaboradoras en Andaluc\u00eda: grandes proclamaciones, pero poco atrevimiento"}]},{"@type":"WebSite","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#website","url":"https:\/\/www.gobiernolocal.org\/acento-local\/","name":"Fundaci\u00f3n Democracia y Gobierno Local","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gobiernolocal.org\/acento-local\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#organization","name":"Fundaci\u00f3n Democracia y Gobierno Local","url":"https:\/\/www.gobiernolocal.org\/acento-local\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/","url":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png","contentUrl":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-content\/uploads\/2024\/09\/logo-acentoo-local.png","width":1005,"height":197,"caption":"Fundaci\u00f3n Democracia y Gobierno Local"},"image":{"@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/022a0a6b36f62f7070403c5a3426d58c","name":"Fundaci\u00f3n Gobierno Local","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gobiernolocal.org\/acento-local\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fa5dea6ae65ded9475a6c7160b1cbc7af5bb19e5a8057c4249aa3664c5fbb21?s=96&d=mm&r=g","caption":"Fundaci\u00f3n Gobierno Local"},"sameAs":["https:\/\/www.gobiernolocal.org\/acento-local"],"url":"https:\/\/www.gobiernolocal.org\/acento-local\/author\/fundacion-gobierno-local\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts\/3784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/comments?post=3784"}],"version-history":[{"count":0,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/posts\/3784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/media\/3786"}],"wp:attachment":[{"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/media?parent=3784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/categories?post=3784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/tags?post=3784"},{"taxonomy":"autor-post","embeddable":true,"href":"https:\/\/www.gobiernolocal.org\/acento-local\/wp-json\/wp\/v2\/autor-post?post=3784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}